{"id":1202,"date":"2026-01-15T10:23:45","date_gmt":"2026-01-15T15:23:45","guid":{"rendered":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/gallery\/m2020-95-15-7-9675_20260112-p2_ra_900px-2\/"},"modified":"2026-05-13T10:49:47","modified_gmt":"2026-05-13T14:49:47","slug":"caitlyn-jenner","status":"publish","type":"csat-media-element","link":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/fr\/galerie\/caitlyn-jenner\/","title":{"rendered":"Caitlyn Jenner"},"featured_media":1198,"menu_order":99,"template":"","meta":{"_acf_changed":false,"image":1198,"media-type":"image","audio":0,"video":0,"credits":"Don de La Presse inc., M2020.95.15.7.9675, Mus\u00e9e McCord Stewart","caption":"Saut \u00e0 hauteur de Caitlyn Jenner au d\u00e9cathlon, 29 juillet 1976","description":"<em>Saut \u00e0 hauteur de Caitlyn Jenner au d\u00e9cathlon, Montr\u00e9al, Qu\u00e9bec<\/em>\r\nRobert Nadon\r\n29 juillet 1976\r\nPhotographie","_thumbnail_id":1198},"class_list":["post-1202","csat-media-element","type-csat-media-element","status-publish","has-post-thumbnail","hentry","csat-media-element-type-image-fr","csat-chapter-usage-chapitre-13"],"media_element_thumbnail":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-content\/uploads\/sites\/183\/2026\/01\/m2020951579675-20260112-p2-ra-900px-150x150.jpg","acf":[],"lang":"fr","translations":{"fr":1202,"en":1200},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element\/1202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element"}],"about":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/types\/csat-media-element"}],"version-history":[{"count":10,"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element\/1202\/revisions"}],"predecessor-version":[{"id":5377,"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element\/1202\/revisions\/5377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/media\/1198"}],"wp:attachment":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/media?parent=1202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}