{"id":1269,"date":"2026-01-15T14:28:25","date_gmt":"2026-01-15T19:28:25","guid":{"rendered":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/gallery\/m2020-95-15-4-939_20260112-p2_ra_1000px\/"},"modified":"2026-05-15T12:50:43","modified_gmt":"2026-05-15T16:50:43","slug":"olympic-stadium","status":"publish","type":"csat-media-element","link":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/en\/gallery\/olympic-stadium\/","title":{"rendered":"Olympic Stadium"},"featured_media":1236,"menu_order":163,"template":"","meta":{"_acf_changed":false,"image":1236,"media-type":"image","audio":0,"video":0,"credits":"Gift of La Presse Inc., M2020.95.15.4.939, McCord Stewart Museum","caption":"The Olympic Stadium construction site, April 5, 1976","description":"<em>The Olympic Stadium construction site, Montreal, Quebec<\/em>\r\nPierre McCann\r\nApril 5, 1976\r\nPhotograph","_thumbnail_id":1236},"class_list":["post-1269","csat-media-element","type-csat-media-element","status-publish","has-post-thumbnail","hentry","csat-media-element-type-image","csat-chapter-usage-chapter-3"],"media_element_thumbnail":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-content\/uploads\/sites\/183\/2026\/01\/m202095154939-20260112-p2-ra-1000px-150x150.jpg","acf":[],"lang":"en","translations":{"en":1269,"fr":1271},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element\/1269","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element"}],"about":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/types\/csat-media-element"}],"version-history":[{"count":8,"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element\/1269\/revisions"}],"predecessor-version":[{"id":5859,"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element\/1269\/revisions\/5859"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/media\/1236"}],"wp:attachment":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/media?parent=1269"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}