{"id":1431,"date":"2026-01-16T13:39:19","date_gmt":"2026-01-16T18:39:19","guid":{"rendered":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/gallery\/m2020-95-15-6-2597_20260114-p2_ra_1000px\/"},"modified":"2026-05-12T14:55:16","modified_gmt":"2026-05-12T18:55:16","slug":"manifestation","status":"publish","type":"csat-media-element","link":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/fr\/galerie\/manifestation\/","title":{"rendered":"Manifestation"},"featured_media":1425,"menu_order":83,"template":"","meta":{"_acf_changed":false,"image":1425,"media-type":"image","audio":0,"video":0,"credits":"Don de La Presse inc., M2020.95.15.6.2597, Mus\u00e9e McCord Stewart","caption":"Manifestation contre les r\u00e9pressions envers la communaut\u00e9 homosexuelle au square Dorchester, 19 juin 1976","description":"<em>Manifestation contre les r\u00e9pressions envers la communaut\u00e9 homosexuelle au square Dorchester, Montr\u00e9al, Qu\u00e9bec<\/em>\r\nRobert Nadon\r\n19 juin 1976\r\nPhotographie","_thumbnail_id":1425},"class_list":["post-1431","csat-media-element","type-csat-media-element","status-publish","has-post-thumbnail","hentry","csat-media-element-type-image-fr","csat-chapter-usage-chapitre-9"],"media_element_thumbnail":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-content\/uploads\/sites\/183\/2026\/01\/m2020951562597-20260114-p2-ra-1000px-150x150.jpg","acf":[],"lang":"fr","translations":{"fr":1431,"en":1433},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element\/1431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element"}],"about":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/types\/csat-media-element"}],"version-history":[{"count":10,"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element\/1431\/revisions"}],"predecessor-version":[{"id":5275,"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element\/1431\/revisions\/5275"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/media\/1425"}],"wp:attachment":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/media?parent=1431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}