{"id":1770,"date":"2026-01-21T12:55:39","date_gmt":"2026-01-21T17:55:39","guid":{"rendered":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/gallery\/m2020-95-15-8-3320_20260112-p2_ra_1000px-2\/"},"modified":"2026-05-13T12:04:54","modified_gmt":"2026-05-13T16:04:54","slug":"ceremonie-de-cloture","status":"publish","type":"csat-media-element","link":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/fr\/galerie\/ceremonie-de-cloture\/","title":{"rendered":"C\u00e9r\u00e9monie de cl\u00f4ture"},"featured_media":1766,"menu_order":120,"template":"","meta":{"_acf_changed":false,"image":1766,"media-type":"image","audio":0,"video":0,"credits":"Don de La Presse inc., M2020.95.15.8.3320, Mus\u00e9e McCord Stewart","caption":"Le c\u00e9r\u00e9monie de cl\u00f4ture des Jeux olympiques, 1er ao\u00fbt 1976","description":"<em>Le c\u00e9r\u00e9monie de cl\u00f4ture des Jeux olympiques, Montr\u00e9al, Qu\u00e9bec<\/em>\r\nPierre McCann\r\n1er ao\u00fbt 1976\r\nPhotographie","_thumbnail_id":1766},"class_list":["post-1770","csat-media-element","type-csat-media-element","status-publish","has-post-thumbnail","hentry","csat-media-element-type-image-fr","csat-chapter-usage-chapitre-17"],"media_element_thumbnail":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-content\/uploads\/sites\/183\/2026\/01\/m2020951583320-20260112-p2-ra-1000px-150x150.jpg","acf":[],"lang":"fr","translations":{"fr":1770,"en":1768},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element\/1770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element"}],"about":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/types\/csat-media-element"}],"version-history":[{"count":10,"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element\/1770\/revisions"}],"predecessor-version":[{"id":5484,"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element\/1770\/revisions\/5484"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/media\/1766"}],"wp:attachment":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/media?parent=1770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}