{"id":1801,"date":"2026-01-21T13:47:55","date_gmt":"2026-01-21T18:47:55","guid":{"rendered":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/gallery\/jo-1976_dji_008_20251009-p1_ra_1000px\/"},"modified":"2026-05-13T12:14:37","modified_gmt":"2026-05-13T16:14:37","slug":"olympic-park-2","status":"publish","type":"csat-media-element","link":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/en\/gallery\/olympic-park-2\/","title":{"rendered":"Olympic Park"},"featured_media":1781,"menu_order":207,"template":"","meta":{"_acf_changed":false,"image":1781,"media-type":"image","audio":0,"video":0,"credits":"Roger Aziz \u00a9 McCord Stewart Museum, 2025","caption":"The Olympic Park, October 2, 2025","description":"<em>The Olympic Park, Montreal, Quebec<\/em>\r\nRoger Aziz\r\nOctober 2, 2025\r\nPhotograph","_thumbnail_id":1781},"class_list":["post-1801","csat-media-element","type-csat-media-element","status-publish","has-post-thumbnail","hentry","csat-media-element-type-image","csat-chapter-usage-chapter-20"],"media_element_thumbnail":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-content\/uploads\/sites\/183\/2026\/01\/jo-1976-dji-008-20251009-p1-ra-1000px-150x150.jpg","acf":[],"lang":"en","translations":{"en":1801,"fr":1803},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element\/1801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element"}],"about":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/types\/csat-media-element"}],"version-history":[{"count":5,"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element\/1801\/revisions"}],"predecessor-version":[{"id":5499,"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element\/1801\/revisions\/5499"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/media\/1781"}],"wp:attachment":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/media?parent=1801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}