{"id":1817,"date":"2026-01-21T13:48:15","date_gmt":"2026-01-21T18:48:15","guid":{"rendered":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/gallery\/m2009-80-51-p1_1000px\/"},"modified":"2026-05-13T12:27:14","modified_gmt":"2026-05-13T16:27:14","slug":"rapport-malouf-2","status":"publish","type":"csat-media-element","link":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/fr\/galerie\/rapport-malouf-2\/","title":{"rendered":"Rapport Malouf"},"featured_media":1785,"menu_order":128,"template":"","meta":{"_acf_changed":false,"image":1785,"media-type":"image","audio":0,"video":0,"credits":"Don de Roland Pierre, M2009.80.50, Mus\u00e9e McCord Stewart","caption":"Silence persistant de Drapeau \u00e0 l'\u00e9gard du rapport Malouf","description":"<em>Silence persistant de Drapeau \u00e0 l'\u00e9gard du rapport Malouf<\/em>\r\nR. Pier\r\n<em>Le Journal de Montr\u00e9al<\/em>, 18 juin 1980\r\nCaricature","_thumbnail_id":1785},"class_list":["post-1817","csat-media-element","type-csat-media-element","status-publish","has-post-thumbnail","hentry","csat-media-element-type-image-fr","csat-chapter-usage-chapitre-19"],"media_element_thumbnail":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-content\/uploads\/sites\/183\/2026\/01\/m20098051-p1-1000px-150x150.jpg","acf":[],"lang":"fr","translations":{"fr":1817,"en":1819},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element\/1817","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element"}],"about":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/types\/csat-media-element"}],"version-history":[{"count":5,"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element\/1817\/revisions"}],"predecessor-version":[{"id":5521,"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element\/1817\/revisions\/5521"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/media\/1785"}],"wp:attachment":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/media?parent=1817"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}