{"id":1993,"date":"2026-01-22T16:03:13","date_gmt":"2026-01-22T21:03:13","guid":{"rendered":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/gallery\/m976-23-13_20260114-p4_ld_1000px\/"},"modified":"2026-06-05T10:10:24","modified_gmt":"2026-06-05T14:10:24","slug":"rain-poncho","status":"publish","type":"csat-media-element","link":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/en\/gallery\/rain-poncho\/","title":{"rendered":"Rain poncho"},"featured_media":6015,"menu_order":230,"template":"","meta":{"_acf_changed":false,"image":6015,"media-type":"image","audio":0,"video":0,"credits":"Gift of Stanley M. Suttie, M976.23.12-13, McCord Stewart Museum","caption":"Venue staff uniform and rain poncho","description":"Venue staff uniform and rain poncho\r\n1976\r\nWhite Sister Uniform Inc.","_thumbnail_id":6015},"class_list":["post-1993","csat-media-element","type-csat-media-element","status-publish","has-post-thumbnail","hentry","csat-media-element-type-image","csat-chapter-usage-chapter-7"],"media_element_thumbnail":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-content\/uploads\/sites\/183\/2026\/01\/m9762313-20260114-p4-ld-1000px-2-150x150.jpg","acf":[],"lang":"en","translations":{"en":1993,"fr":1995},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element\/1993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element"}],"about":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/types\/csat-media-element"}],"version-history":[{"count":7,"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element\/1993\/revisions"}],"predecessor-version":[{"id":6017,"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element\/1993\/revisions\/6017"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/media\/6015"}],"wp:attachment":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/media?parent=1993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}