{"id":2039,"date":"2026-01-22T16:45:13","date_gmt":"2026-01-22T21:45:13","guid":{"rendered":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/gallery\/m988-176-387_666px\/"},"modified":"2026-05-13T12:57:56","modified_gmt":"2026-05-13T16:57:56","slug":"jean-drapeau","status":"publish","type":"csat-media-element","link":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/en\/gallery\/jean-drapeau\/","title":{"rendered":"Jean Drapeau"},"featured_media":2037,"menu_order":233,"template":"","meta":{"_acf_changed":false,"image":2037,"media-type":"image","audio":0,"video":0,"credits":"Gift of Abner Kushner, M988.176.387, McCord Stewart Museum","caption":"Jean Drapeau is losing control","description":"<em>Jean Drapeau is losing control<\/em>\r\nAislin\r\n<em>The Gazette<\/em>, May 20, 1975\r\nCartoon","_thumbnail_id":2037},"class_list":["post-2039","csat-media-element","type-csat-media-element","status-publish","has-post-thumbnail","hentry","csat-media-element-type-image","csat-chapter-usage-chapter-8"],"media_element_thumbnail":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-content\/uploads\/sites\/183\/2026\/01\/m988176387-666px-150x150.jpg","acf":[],"lang":"en","translations":{"en":2039,"fr":2041},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element\/2039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element"}],"about":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/types\/csat-media-element"}],"version-history":[{"count":6,"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element\/2039\/revisions"}],"predecessor-version":[{"id":5557,"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element\/2039\/revisions\/5557"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/media\/2037"}],"wp:attachment":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/media?parent=2039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}