{"id":2401,"date":"2026-02-03T15:46:00","date_gmt":"2026-02-03T20:46:00","guid":{"rendered":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/gallery\/m976-178-16_20250513-p1_ra_1000px-2\/"},"modified":"2026-05-12T11:25:22","modified_gmt":"2026-05-12T15:25:22","slug":"aviron","status":"publish","type":"csat-media-element","link":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/fr\/galerie\/aviron\/","title":{"rendered":"Aviron"},"featured_media":2334,"menu_order":48,"template":"","meta":{"_acf_changed":false,"image":2334,"media-type":"image","audio":0,"video":0,"credits":"Don du Comit\u00e9 organisateur des Jeux de la XXIe\u202fOlympiade (COJO), M976.178.16, Mus\u00e9e McCord Stewart, \u00a9 COJO 76","caption":"Affiche sportive, <em>Aviron<\/em>","description":"Affiche sportive, <em>Aviron<\/em>\r\nAlbrecht Gaebele et Erwin Fieger (photographes)\r\n1975","_thumbnail_id":2334},"class_list":["post-2401","csat-media-element","type-csat-media-element","status-publish","has-post-thumbnail","hentry","csat-media-element-type-image-fr","csat-chapter-usage-chapitre-6"],"media_element_thumbnail":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-content\/uploads\/sites\/183\/2026\/02\/m97617816-20250513-p1-ra-1000px-150x150.jpg","acf":[],"lang":"fr","translations":{"fr":2401,"en":2399},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element\/2401","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element"}],"about":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/types\/csat-media-element"}],"version-history":[{"count":7,"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element\/2401\/revisions"}],"predecessor-version":[{"id":5104,"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element\/2401\/revisions\/5104"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/media\/2334"}],"wp:attachment":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/media?parent=2401"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}