{"id":2489,"date":"2026-02-04T11:13:54","date_gmt":"2026-02-04T16:13:54","guid":{"rendered":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/gallery\/m2017-10-2-51_20260203-p2_ra_1000px\/"},"modified":"2026-06-16T10:43:14","modified_gmt":"2026-06-16T14:43:14","slug":"flame","status":"publish","type":"csat-media-element","link":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/en\/gallery\/flame\/","title":{"rendered":"Flame"},"featured_media":6228,"menu_order":265,"template":"","meta":{"_acf_changed":false,"image":6228,"media-type":"image","audio":0,"video":0,"credits":"Gift of Jacqueline Bourget-Huel and Carina Marinelli, member in charge of honorary members and archives, Soci\u00e9t\u00e9 des designers graphiques du Qu\u00e9bec, M2017.10.2.51, McCord Stewart Museum","caption":"Route of the Olympic Flame, 1975","description":"<em>Route of the Olympic Flame<\/em>\r\nFran\u00e7ois Dumouchel\r\n1975\r\nTest shot for a poster mock-up","_thumbnail_id":6228},"class_list":["post-2489","csat-media-element","type-csat-media-element","status-publish","has-post-thumbnail","hentry","csat-media-element-type-image","csat-chapter-usage-chapter-10"],"media_element_thumbnail":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-content\/uploads\/sites\/183\/2026\/02\/m201710251-20260203-p2-ra-600px-1-150x150.jpg","acf":[],"lang":"en","translations":{"en":2489,"fr":2491},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element\/2489","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element"}],"about":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/types\/csat-media-element"}],"version-history":[{"count":8,"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element\/2489\/revisions"}],"predecessor-version":[{"id":6230,"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/csat-media-element\/2489\/revisions\/6230"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/media\/6228"}],"wp:attachment":[{"href":"https:\/\/www.histoiresdecheznous.ca\/v3\/olympiques-montreal-1976-olympics\/wp-json\/wp\/v2\/media?parent=2489"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}